{"id":1,"count":64,"description":"","link":"http:\/\/annbe-design.de\/esskultur\/category\/fleisch-fisch\/","name":"Fleisch &amp; Fisch","slug":"fleisch-fisch","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/categories\/1"}],"collection":[{"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}