{"id":11,"date":"2017-04-20T16:05:29","date_gmt":"2017-04-20T14:05:29","guid":{"rendered":"http:\/\/annbe-design.de\/esskulturo\/?p=11"},"modified":"2017-04-24T14:04:28","modified_gmt":"2017-04-24T12:04:28","slug":"11","status":"publish","type":"post","link":"http:\/\/annbe-design.de\/esskultur\/11\/","title":{"rendered":"Gef\u00fcllte Mini-Paprika"},"content":{"rendered":"<h4>Zutaten: (2 Pers.)<\/h4>\n<p>10-14 Mini-Paprika<br \/>\n10-14 kl. Kartoffeln<br \/>\n2 Zwiebeln<br \/>\n1 Knoblauchzehe<br \/>\n1 Bund glatte Petersilie<br \/>\n500 g gemischtes Hack<br \/>\nSalz, Pfeffer<br \/>\n2 El Semmelbr\u00f6sel<br \/>\n2 Eier (Kl. M)<br \/>\n400 ml Fleischbr\u00fche oder<br \/>\nGem\u00fcsebr\u00fche<\/p>\n<h4>Zubereitung: (Zeit: 50 min)<\/h4>\n<p>1. 2 Zwiebeln und 1 Knoblauchzehe fein w\u00fcrfeln. Bl\u00e4tter von 1 Bund glatter Petersilie hacken. Kartoffeln (evtl. sch\u00e4len) halbieren.<\/p>\n<p>2. 500 g gemischtes Hack mit je der H\u00e4lfte der Zwiebeln und der Petersilie, Knoblauch, 2 El Semmelbr\u00f6seln und 2 Eiern (Kl. M) mischen. Salzen und pfeffern.<\/p>\n<p>3. Die Deckel von den Paprikaschoten abschneiden. Kerne und Trennh\u00e4ute aus den Schoten entfernen. Paprika mit Hackmasse f\u00fcllen.<\/p>\n<p>4. 2 El Oliven\u00f6l in einem Br\u00e4ter erhitzen. Restliche Zwiebeln und halbierte Kartoffeln 5 Min. darin d\u00fcnsten, salzen und pfeffern. 400 ml Fleischbr\u00fche zugie\u00dfen, aufkochen und Paprikaschoten und -deckel nebeneinander hineingeben.<\/p>\n<p>5. Im hei\u00dfen Ofen bei 200 Grad im unteren Drittel 25 Min. garen (Umluft nicht empfehlenswert).<\/p>\n<p>&nbsp;<\/p>\n<h4>N\u00e4hrwerte: (pro Pers.)<\/h4>\n<p>500 kcal, 31 g Eiwei\u00df, 30 g Fett, 25 g KH<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"entry-summary\">\nZutaten: (2 Pers.) 10-14 Mini-Paprika 10-14 kl. Kartoffeln 2 Zwiebeln 1 Knoblauchzehe&hellip;\n<\/div>\n<div class=\"link-more\"><a href=\"http:\/\/annbe-design.de\/esskultur\/11\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &ldquo;Gef\u00fcllte Mini-Paprika&rdquo;<\/span>&hellip;<\/a><\/div>\n","protected":false},"author":1,"featured_media":63,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,6],"tags":[],"_links":{"self":[{"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/posts\/11"}],"collection":[{"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":3,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/posts\/11\/revisions"}],"predecessor-version":[{"id":64,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/posts\/11\/revisions\/64"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/media\/63"}],"wp:attachment":[{"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/media?parent=11"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/categories?post=11"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/tags?post=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}