{"id":195,"date":"2017-04-26T14:11:23","date_gmt":"2017-04-26T12:11:23","guid":{"rendered":"http:\/\/annbe-design.de\/esskulturo\/?p=195"},"modified":"2017-05-08T11:39:50","modified_gmt":"2017-05-08T09:39:50","slug":"mini-burger-broetchen","status":"publish","type":"post","link":"http:\/\/annbe-design.de\/esskultur\/mini-burger-broetchen\/","title":{"rendered":"Mini-Burger-Br\u00f6tchen"},"content":{"rendered":"<h4>Zutaten: (10 Burger\/Br\u00f6tchen)<\/h4>\n<p><strong>F\u00fcr die Br\u00f6tchen:<\/strong><\/p>\n<p>500 g Mehl<br \/>\neine gro\u00dfe Prise Salz<br \/>\neinen Essl\u00f6ffel Zucker<br \/>\n25 g Schmalz<br \/>\n200 ml Milch<br \/>\n100 ml Wasser<br \/>\n5 g Hefe<br \/>\n1 Ei<br \/>\nSesam<\/p>\n<p><strong>F\u00fcr die Burger:<\/strong><\/p>\n<p>400 g Rinderhack<br \/>\nZwiebeln<br \/>\nSchmelzk\u00e4se<\/p>\n<h4>Zubereitung:<\/h4>\n<p><strong>Br\u00f6tchen: (Zeit: 140 min)<\/strong><\/p>\n<p>1. 500 g Mehl, eine gro\u00dfe Prise Salz und einen Essl\u00f6ffel Zucker in eine Sch\u00fcssel geben. 25 g Schmalz, 200 ml Milch und 100 ml lauwarmes Wasser mit 5 g Hefe hinzugeben.<\/p>\n<p>2. Wenn alle Zutaten gut vermischt sind, die Masse auf die Arbeitsfl\u00e4che kippen und f\u00fcr mindestens 15 Minuten gut durch knetet. Eine Stunde abgedeckt im Warmen ruhen lassen.<\/p>\n<p>3. Dann den Teig in 10 gleich gro\u00dfe St\u00fccke zerteilen, Kugeln formen, ausrollen und auf ein Backblech mit Backpapier legen. Mit Ei bestreichen und nochmals abdecken. &#8211; Eine halbe Stunde im Warmen lassen. &#8211; Ein zweites Mal mit Ei bestreichen und mit etwas Sesam bestreuen. Jetzt eine halbe Stunde gehen lassen, bis die Kugeln ganz aufgegangen sind.<\/p>\n<p>Ab in den Ofen &#8211; bei 200 Grad f\u00fcr 10 Minuten.<\/p>\n<p><strong>Burger: (Zeit: 20 min)<\/strong><\/p>\n<p>1. Zwiebeln in d\u00fcnne St\u00fcckchen schneiden und zum Rinderhack geben. Dann Fleischb\u00e4llchen formen und platt dr\u00fccken. Dann von au\u00dfen gut salzen und pfeffern.<\/p>\n<p>2. Etwas \u00d6l in die Pfanne geben. Die Burge zwei Minuten beidseitig gut anbraten.<\/p>\n<p>3. K\u00e4se auf das Fleisch in der Pfanne geben. Die Br\u00f6tchen halbieren und auf die Burger f\u00fcr etwa 20 Sekunden legen.<br \/>\nFertig! Jetzt k\u00f6nnen die Mini-Burger noch nach Belieben mit weiteren Zutaten belegt werden!<\/p>\n<p>&nbsp;<\/p>\n<h4>N\u00e4hrwerte: (pro Pers.)<\/h4>\n<p>390 kcal, 25 g Eiwei\u00df, 24 g Fett, 16 g KH<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"entry-summary\">\nZutaten: (10 Burger\/Br\u00f6tchen) F\u00fcr die Br\u00f6tchen: 500 g Mehl eine gro\u00dfe Prise&hellip;\n<\/div>\n<div class=\"link-more\"><a href=\"http:\/\/annbe-design.de\/esskultur\/mini-burger-broetchen\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &ldquo;Mini-Burger-Br\u00f6tchen&rdquo;<\/span>&hellip;<\/a><\/div>\n","protected":false},"author":1,"featured_media":197,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/posts\/195"}],"collection":[{"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/comments?post=195"}],"version-history":[{"count":2,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/posts\/195\/revisions"}],"predecessor-version":[{"id":366,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/posts\/195\/revisions\/366"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/media\/197"}],"wp:attachment":[{"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/media?parent=195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/categories?post=195"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/tags?post=195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}