{"id":349,"date":"2017-05-05T15:46:42","date_gmt":"2017-05-05T13:46:42","guid":{"rendered":"http:\/\/annbe-design.de\/esskulturo\/?p=349"},"modified":"2019-09-25T15:54:10","modified_gmt":"2019-09-25T13:54:10","slug":"kartoffelsuppe","status":"publish","type":"post","link":"http:\/\/annbe-design.de\/esskultur\/kartoffelsuppe\/","title":{"rendered":"Kartoffelsuppe"},"content":{"rendered":"<h2>mit W\u00fcrstchen<\/h2>\n<h4>Zutaten: (4 Pers.)<\/h4>\n<p>1 gro\u00dfe Zwiebel<br \/>\n1 kg Kartoffeln (am besten eine mehligkochende Sorte)<br \/>\n1,25 l Gem\u00fcsebr\u00fche<br \/>\n1 Lorbeerblatt<br \/>\nSalz, Pfeffer<br \/>\nfrisch geriebene Muskatnuss<br \/>\n100 g Sahne<br \/>\n4-6 Wiener W\u00fcrstchen<\/p>\n<p>1 Bund Suppengem\u00fcse<br \/>\noder:<br \/>\n1 kleine Stange Lauch<br \/>\n2-3 M\u00f6hren (ca. 200 g)<br \/>\n1 St\u00fcck Knollensellerie (ca. 150 g)<br \/>\n1\/2 Bund Petersilie<\/p>\n<p><strong>Wer&#8217;s mag, gibt noch:<\/strong><br \/>\n200g Pfifferlinge<br \/>\n100g Speck<\/p>\n<h4>Zubereitung: (Zeit: 70 min)<\/h4>\n<p>1. Zwiebel sch\u00e4len und w\u00fcrfeln. Lauch putzen, gr\u00fcndlich waschen und in schmale Ringe schneiden. Kartoffeln, M\u00f6hren und Sellerie putzen, sch\u00e4len und grob w\u00fcrfeln.<\/p>\n<p>2. Etwas Butter in einem gro\u00dfen Topf zerlassen und die Zwiebelw\u00fcrfel darin goldgelb and\u00fcnsten. M\u00f6hren- und Selleriew\u00fcrfel dazugeben und unter R\u00fchren ca. 2 Min. mitd\u00fcnsten. Die Br\u00fche dazugie\u00dfen. Lauch, Kartoffelw\u00fcrfel und Lorbeerblatt hinzuf\u00fcgen, alles mit Salz, Pfeffer und Muskatnuss w\u00fcrzen und aufkochen. Die Suppe bei kleiner Hitze im geschlossenen Topf ca. 25 Min. k\u00f6cheln lassen.<\/p>\n<p>3. Das Lorbeerblatt entfernen. Zwei Kellen Gem\u00fcse aus dem Topf nehmen und den Rest der Suppe mit dem P\u00fcrierstab p\u00fcrieren. Danach die Gem\u00fcsest\u00fccke wieder unter die Suppe r\u00fchren. Wer die Suppe sehr fein und cremig mag, p\u00fcriert die ganze Menge. Die Sahne unterr\u00fchren, die Suppe mit Salz, Pfeffer und Muskatnuss abschmecken.<\/p>\n<p>4. Die W\u00fcrsten in scheiben schneiden und zur Suppe geben. Pfifferlinge und Speck auch zur Suppe geben. Noch mal 5 min bei mittler hitze k\u00f6cheln lassen.<br \/>\nDie Suppe mit Petersilie servieren.<\/p>\n<p>&nbsp;<\/p>\n<h4>N\u00e4hrwerte: (pro Pers.)<\/h4>\n<p>520 kcal, 8 g Eiwei\u00df, 12 g Fett, 28 g KH<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"entry-summary\">\nmit W\u00fcrstchen Zutaten: (4 Pers.) 1 gro\u00dfe Zwiebel 1 kg Kartoffeln (am&hellip;\n<\/div>\n<div class=\"link-more\"><a href=\"http:\/\/annbe-design.de\/esskultur\/kartoffelsuppe\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &ldquo;Kartoffelsuppe&rdquo;<\/span>&hellip;<\/a><\/div>\n","protected":false},"author":1,"featured_media":350,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/posts\/349"}],"collection":[{"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/comments?post=349"}],"version-history":[{"count":2,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/posts\/349\/revisions"}],"predecessor-version":[{"id":660,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/posts\/349\/revisions\/660"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/media\/350"}],"wp:attachment":[{"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/media?parent=349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/categories?post=349"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/tags?post=349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}