{"id":742,"date":"2021-09-16T09:31:29","date_gmt":"2021-09-16T07:31:29","guid":{"rendered":"http:\/\/annbe-design.de\/esskultur\/?p=742"},"modified":"2021-09-16T09:32:32","modified_gmt":"2021-09-16T07:32:32","slug":"nudeln-mit-garnelen-und-tomaten-sahnesauce","status":"publish","type":"post","link":"http:\/\/annbe-design.de\/esskultur\/nudeln-mit-garnelen-und-tomaten-sahnesauce\/","title":{"rendered":"Nudeln mit Garnelen in Tomaten-Sahnesauce"},"content":{"rendered":"<h4>Zutaten: (2 Pers.)<\/h4>\n<div class=\"wprm-recipe-ingredient-group\">\n<p><span class=\"wprm-recipe-ingredient-amount\">300<\/span> <span class=\"wprm-recipe-ingredient-unit\">g<\/span> <span class=\"wprm-recipe-ingredient-name\">Nudeln<br \/>\n<\/span><span class=\"wprm-recipe-ingredient-amount\">2<\/span> <span class=\"wprm-recipe-ingredient-name\">Knoblauchzehen<br \/>\n<\/span><span class=\"wprm-recipe-ingredient-amount\">2-3<\/span> <span class=\"wprm-recipe-ingredient-name\">rote Chilischoten<br \/>\n<\/span><span class=\"wprm-recipe-ingredient-amount\">3<\/span> <span class=\"wprm-recipe-ingredient-name\">Fr\u00fchlingszwiebeln<br \/>\n<\/span><span class=\"wprm-recipe-ingredient-amount\">3<\/span> <span class=\"wprm-recipe-ingredient-unit\">EL<\/span> <span class=\"wprm-recipe-ingredient-name\">Oliven\u00f6l<br \/>\n<\/span><span class=\"wprm-recipe-ingredient-amount\">300<\/span> <span class=\"wprm-recipe-ingredient-unit\">g<\/span> <span class=\"wprm-recipe-ingredient-name\">k\u00fcchenfertige Scampi<br \/>\n<\/span><span class=\"wprm-recipe-ingredient-amount\">150<\/span> <span class=\"wprm-recipe-ingredient-unit\">ml<\/span> <span class=\"wprm-recipe-ingredient-name\">Sahne<br \/>\n<\/span><span class=\"wprm-recipe-ingredient-amount\">125<\/span> <span class=\"wprm-recipe-ingredient-unit\">ml<\/span> <span class=\"wprm-recipe-ingredient-name\">trockener Wei\u00dfwein<br \/>\n<\/span><span class=\"wprm-recipe-ingredient-amount\">4<\/span> <span class=\"wprm-recipe-ingredient-unit\">EL<\/span> <span class=\"wprm-recipe-ingredient-name\">Tomatenmark<br \/>\n<\/span><span class=\"wprm-recipe-ingredient-name\">Salz und Pfeffer<\/span><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<h4>Zubereitung: (Zeit: 20 min)<\/h4>\n<p>1. Pasta in reichlich Salzwasser al dente garen.<\/p>\n<p>2. In der Zwischenzeit Knoblauch sch\u00e4len und hacken. Chili und Fr\u00fchlingszwiebeln waschen. Chili hacken, Fr\u00fchlingszwiebeln in R\u00f6llchen schneiden. Scampi mit K\u00fcchenpapier trocken tupfen.<\/p>\n<p>3. Oliven\u00f6l in einer Pfanne erhitzen und Scampis anbraten. Knoblauch, Chili, Wei\u00dfwein, Sahne, Tomatenmark und Fr\u00fchlingszwiebeln hinzuf\u00fcgen. Zwei Minuten einkochen lassen. Gut mit Salz und Pfeffer abschmecken.<\/p>\n<p>4. Nudeln hinzuf\u00fcgen und alles vermischen. Noch einmal mit Salz und Pfeffer abschmecken. Servieren.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>N\u00e4hrwerte: (pro Pers.)<\/p>\n<p>690 kcal, 30 g Eiwei\u00df, 26 g Fett, 80 g KH<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"entry-summary\">\nZutaten: (2 Pers.) 300 g Nudeln 2 Knoblauchzehen 2-3 rote Chilischoten 3&hellip;\n<\/div>\n<div class=\"link-more\"><a href=\"http:\/\/annbe-design.de\/esskultur\/nudeln-mit-garnelen-und-tomaten-sahnesauce\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &ldquo;Nudeln mit Garnelen in Tomaten-Sahnesauce&rdquo;<\/span>&hellip;<\/a><\/div>\n","protected":false},"author":1,"featured_media":743,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/posts\/742"}],"collection":[{"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/comments?post=742"}],"version-history":[{"count":3,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/posts\/742\/revisions"}],"predecessor-version":[{"id":746,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/posts\/742\/revisions\/746"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/media\/743"}],"wp:attachment":[{"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/media?parent=742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/categories?post=742"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/annbe-design.de\/esskultur\/wp-json\/wp\/v2\/tags?post=742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}